{"id":1634,"date":"2019-09-27T17:59:07","date_gmt":"2019-09-27T15:59:07","guid":{"rendered":"https:\/\/www.sutermeister.ch\/la-mediation-culturelle-dans-les-arts-de-la-scene\/"},"modified":"2020-01-20T19:39:02","modified_gmt":"2020-01-20T18:39:02","slug":"la-mediation-culturelle-dans-les-arts-de-la-scene","status":"publish","type":"post","link":"https:\/\/www.sutermeister.ch\/en\/la-mediation-culturelle-dans-les-arts-de-la-scene\/","title":{"rendered":"La m\u00e9diation culturelle dans les arts de la sc\u00e8ne"},"content":{"rendered":"<p>Depuis quelques ann\u00e9es, les collectivit\u00e9s publiques suisses t\u00e9moignent d\u2019un int\u00e9r\u00eat croissant pour la question des publics. Apr\u00e8s avoir d\u00e9velopp\u00e9 puis renforc\u00e9 au cours des derni\u00e8res d\u00e9cennies les institutions et mis en place des instruments de soutien \u00e0 la cr\u00e9ation (soutiens ponctuels, conventions de soutien pluriannuels), elles s\u2019int\u00e9ressent aujourd\u2019hui aux destinataires des offres culturelles : Qui sont-ils ? Dans quelles cat\u00e9gories socio-professionnelles s\u2019inscrivent-ils ? Quelles sont leurs pratiques culturelles ?<\/p>\n<p><a href=\"https:\/\/www.sutermeister.ch\/site\/wp-content\/uploads\/2019\/09\/Actes-du-colloque-La-me\u0301diation-dans-les-arts-de-la-sce\u0300ne.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Actes du colloque &#8211; La me\u0301diation dans les arts de la sce\u0300ne<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis quelques ann\u00e9es, les collectivit\u00e9s publiques suisses t\u00e9moignent d\u2019un int\u00e9r\u00eat croissant pour la question des publics. Apr\u00e8s avoir d\u00e9velopp\u00e9 puis renforc\u00e9 au cours des derni\u00e8res d\u00e9cennies les institutions et mis en place des instruments de soutien \u00e0 la cr\u00e9ation (soutiens ponctuels, conventions de soutien pluriannuels),&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[32],"tags":[],"class_list":["post-1634","post","type-post","status-publish","format-standard","hentry","category-articles-en"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sutermeister.ch\/en\/wp-json\/wp\/v2\/posts\/1634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sutermeister.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sutermeister.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sutermeister.ch\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sutermeister.ch\/en\/wp-json\/wp\/v2\/comments?post=1634"}],"version-history":[{"count":1,"href":"https:\/\/www.sutermeister.ch\/en\/wp-json\/wp\/v2\/posts\/1634\/revisions"}],"predecessor-version":[{"id":1635,"href":"https:\/\/www.sutermeister.ch\/en\/wp-json\/wp\/v2\/posts\/1634\/revisions\/1635"}],"wp:attachment":[{"href":"https:\/\/www.sutermeister.ch\/en\/wp-json\/wp\/v2\/media?parent=1634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sutermeister.ch\/en\/wp-json\/wp\/v2\/categories?post=1634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sutermeister.ch\/en\/wp-json\/wp\/v2\/tags?post=1634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}